
{"id":175422,"date":"2024-05-29T10:03:31","date_gmt":"2024-05-29T08:03:31","guid":{"rendered":"https:\/\/wrzecionoczasu.pl\/warsaw-salon\/"},"modified":"2026-01-20T16:51:20","modified_gmt":"2026-01-20T15:51:20","slug":"warsaw-salon","status":"publish","type":"page","link":"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/","title":{"rendered":"Warsaw Salon"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"175422\" class=\"elementor elementor-175422 elementor-28732\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44f3128 e-flex e-con-boxed e-con e-parent\" data-id=\"44f3128\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a992bae elementor-widget elementor-widget-html\" data-id=\"a992bae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- SLIDER ZDJ\u0118\u0106 SALONU \u2013 FINAL (ODSUNI\u0118TY OD HEADERA) -->\r\n<div class=\"wc-salon\" data-autoplay=\"0\">\r\n  <div class=\"wc-salon__viewport\">\r\n    <div class=\"wc-salon__track\" id=\"wcSalonTrack\"><\/div>\r\n  <\/div>\r\n\r\n  <button class=\"wc-salon__nav wc-salon__prev\" type=\"button\" aria-label=\"Poprzedni\">\u2039<\/button>\r\n  <button class=\"wc-salon__nav wc-salon__next\" type=\"button\" aria-label=\"Nast\u0119pny\">\u203a<\/button>\r\n\r\n  <div class=\"wc-salon__dots\" id=\"wcSalonDots\"><\/div>\r\n<\/div>\r\n\r\n<script>\r\n(function(){\r\n  let IMAGES = [\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010072.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010070.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010066-HDR.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010063-HDR.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010058.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010052.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010048-HDR.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010045-HDR.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010042-HDR.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010039-HDR.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010036-HDR.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010033-HDR.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010030-HDR.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010027-HDR-2.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010021-HDR.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010015-HDR-2.jpg\",\r\n    \"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/01\/L1010009-HDR.jpg\"\r\n  ];\r\n\r\n  \/* LOSOWA KOLEJNO\u015a\u0106 *\/\r\n  for (let i = IMAGES.length - 1; i > 0; i--) {\r\n    const j = Math.floor(Math.random() * (i + 1));\r\n    [IMAGES[i], IMAGES[j]] = [IMAGES[j], IMAGES[i]];\r\n  }\r\n\r\n  const root  = document.querySelector('.wc-salon');\r\n  const track = document.getElementById('wcSalonTrack');\r\n  const dots  = document.getElementById('wcSalonDots');\r\n  const prev  = root.querySelector('.wc-salon__prev');\r\n  const next  = root.querySelector('.wc-salon__next');\r\n\r\n  IMAGES.forEach((src, i) => {\r\n    const slide = document.createElement('a');\r\n    slide.href = src;\r\n    slide.target = \"_blank\";\r\n    slide.rel = \"noopener\";\r\n    slide.className = \"wc-salon__slide\";\r\n\r\n    const img = document.createElement('img');\r\n    img.src = src;\r\n    img.loading = \"lazy\";\r\n    img.alt = \"Salon Wrzeciono Czasu \u2013 zdj\u0119cie \" + (i+1);\r\n\r\n    slide.appendChild(img);\r\n    track.appendChild(slide);\r\n\r\n    const dot = document.createElement('button');\r\n    dot.className = \"wc-salon__dot\";\r\n    dot.onclick = () => goTo(i);\r\n    dots.appendChild(dot);\r\n  });\r\n\r\n  let index = 0;\r\n\r\n  function slidesPerView(){\r\n    if (window.innerWidth <= 1024) return 1;\r\n    return 3;\r\n  }\r\n\r\n  function maxIndex(){\r\n    return Math.max(0, IMAGES.length - slidesPerView());\r\n  }\r\n\r\n  function step(){\r\n    const s = track.querySelector('.wc-salon__slide');\r\n    const gap = parseFloat(getComputedStyle(track).gap) || 0;\r\n    return s.getBoundingClientRect().width + gap;\r\n  }\r\n\r\n  function update(){\r\n    track.style.transform = `translateX(${-index * step()}px)`;\r\n    [...dots.children].forEach((d,i)=>d.classList.toggle('is-active', i===index));\r\n    prev.disabled = index === 0;\r\n    next.disabled = index === maxIndex();\r\n  }\r\n\r\n  function goTo(i){\r\n    index = Math.max(0, Math.min(i, maxIndex()));\r\n    update();\r\n  }\r\n\r\n  prev.onclick = () => goTo(index - 1);\r\n  next.onclick = () => goTo(index + 1);\r\n  window.addEventListener('resize', update);\r\n\r\n  update();\r\n})();\r\n<\/script>\r\n\r\n<style>\r\n\/* === ODSUNI\u0118CIE OD G\u00d3RNEGO PASKA === *\/\r\n.wc-salon{\r\n  position:relative;\r\n  max-width:1400px;\r\n  margin:48px auto 40px;   \/* \ud83d\udd25 TO JEST KLUCZOWE *\/\r\n  padding:0 16px;\r\n}\r\n\r\n\/* TRACK *\/\r\n.wc-salon__viewport{overflow:hidden;}\r\n.wc-salon__track{\r\n  display:flex;\r\n  gap:12px;\r\n  transition:transform .45s ease;\r\n}\r\n\r\n\/* SLIDE *\/\r\n.wc-salon__slide{\r\n  flex:0 0 calc(33.333% - 8px);\r\n  aspect-ratio:16 \/ 11;\r\n  overflow:hidden;\r\n  border-radius:18px;\r\n  box-shadow:0 10px 32px rgba(0,0,0,.12);\r\n}\r\n.wc-salon__slide img{\r\n  width:100%;\r\n  height:100%;\r\n  object-fit:cover;\r\n}\r\n\r\n\/* STRZA\u0141KI *\/\r\n.wc-salon__nav{\r\n  position:absolute;\r\n  top:50%;\r\n  transform:translateY(-50%);\r\n  width:46px;\r\n  height:46px;\r\n  border-radius:50%;\r\n  background:#fff;\r\n  border:0;\r\n  font-size:30px;\r\n  cursor:pointer;\r\n}\r\n.wc-salon__prev{left:-12px;}\r\n.wc-salon__next{right:-12px;}\r\n\r\n\/* KROPKI *\/\r\n.wc-salon__dots{\r\n  display:flex;\r\n  gap:8px;\r\n  justify-content:center;\r\n  margin-top:18px;\r\n}\r\n.wc-salon__dot{\r\n  width:8px;\r\n  height:8px;\r\n  border-radius:50%;\r\n  background:#c8c8c8;\r\n  border:0;\r\n}\r\n.wc-salon__dot.is-active{background:#333;}\r\n\r\n\/* TABLET + MOBILE *\/\r\n@media (max-width:1024px){\r\n  .wc-salon__slide{flex:0 0 100%;}\r\n}\r\n\r\n\/* MOBILE *\/\r\n@media (max-width:640px){\r\n  .wc-salon{\r\n    margin-top:64px;   \/* \ud83d\udd25 WI\u0118CEJ MIEJSCA POD HEADEREM NA TELEFONIE *\/\r\n    padding:0 12px;\r\n  }\r\n\r\n  .wc-salon__slide{\r\n    aspect-ratio:4 \/ 3;\r\n    border-radius:14px;\r\n  }\r\n\r\n  .wc-salon__nav{\r\n    width:38px;\r\n    height:38px;\r\n    font-size:24px;\r\n    opacity:0.9;\r\n  }\r\n  .wc-salon__prev{left:6px;}\r\n  .wc-salon__next{right:6px;}\r\n\r\n  .wc-salon__dots{margin-top:12px;}\r\n}\r\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-488459c e-flex e-con-boxed e-con e-parent\" data-id=\"488459c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4b70729 e-con-full e-flex e-con e-child\" data-id=\"4b70729\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3725de elementor-widget elementor-widget-template\" data-id=\"d3725de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"175459\" class=\"elementor elementor-175459 elementor-27547\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfbd751 e-flex e-con-boxed e-con e-child\" data-id=\"cfbd751\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5efe59e elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"5efe59e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/1JkjE1L87b71umsY7\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"View map \">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewBox=\"0 0 48 48\" fill=\"none\"><path d=\"M0 10C0 4.47715 4.47715 0 10 0H38C43.5229 0 48 4.47715 48 10V38C48 43.5229 43.5228 48 38 48H10C4.47715 48 0 43.5228 0 38V10Z\" fill=\"#BE9850\"><\/path><path d=\"M24 25C25.6569 25 27 23.6569 27 22C27 20.3431 25.6569 19 24 19C22.3431 19 21 20.3431 21 22C21 23.6569 22.3431 25 24 25Z\" stroke=\"white\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M24 34C28 30 32 26.4183 32 22C32 17.5817 28.4183 14 24 14C19.5817 14 16 17.5817 16 22C16 26.4183 20 30 24 34Z\" stroke=\"white\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/1JkjE1L87b71umsY7\" target=\"_blank\" >\n\t\t\t\t\t\t\tView map \t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2512f90 elementor-widget elementor-widget-heading\" data-id=\"2512f90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warsaw<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41b2558 elementor-widget elementor-widget-text-editor\" data-id=\"41b2558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mokotowska 71 unit 101<br>00-530 Warsaw<br>Opening hours:<br>Monday &#8211; Friday 11:00 AM-7:00 PM<br>Saturday 11:00 AM-5:00 PM<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b149eab elementor-widget elementor-widget-text-editor\" data-id=\"b149eab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Email<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3068a4 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e3068a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:wrzeciono_czasu@wp.pl\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">wrzeciono_czasu@wp.pl<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0da2194 elementor-widget elementor-widget-text-editor\" data-id=\"0da2194\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Helpline<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00de219 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"00de219\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:512%20301%20928\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+48 512 301 928<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e241397 elementor-widget elementor-widget-text-editor\" data-id=\"e241397\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>EXTENSION 1, SERVICE EXTENSION 5<\/p><p>Unable to respond to SMS and WhatsApp messages. This number is for call forwarding and phone calls only. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a00cdf6 e-con-full e-flex e-con e-child\" data-id=\"a00cdf6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de94101 elementor-widget elementor-widget-google_maps\" data-id=\"de94101\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Wrzeciono%20Czasu%20-%20Serwis&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Wrzeciono Czasu - Serwis\"\n\t\t\t\t\taria-label=\"Wrzeciono Czasu - Serwis\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e2cdc96 e-con-full e-flex e-con e-parent\" data-id=\"e2cdc96\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0918013 elementor-widget elementor-widget-heading\" data-id=\"0918013\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Below we present a map of Mokotowska Street with marked parking areas, kindly provided by our partner local newspaper Ave Mokotowska.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60fd22f elementor-widget elementor-widget-image\" data-id=\"60fd22f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"581\" src=\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2025\/12\/mprzystal_avemokotowska_mapa-1024x744-1.png\" class=\"attachment-large size-large wp-image-188745\" alt=\"\" srcset=\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2025\/12\/mprzystal_avemokotowska_mapa-1024x744-1.png 1024w, https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2025\/12\/mprzystal_avemokotowska_mapa-1024x744-1-300x218.png 300w, https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2025\/12\/mprzystal_avemokotowska_mapa-1024x744-1-768x558.png 768w, https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2025\/12\/mprzystal_avemokotowska_mapa-1024x744-1-600x436.png 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b54cd7 elementor-widget elementor-widget-template\" data-id=\"4b54cd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"175415\" class=\"elementor elementor-175415 elementor-28734\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d17e158 e-flex e-con-boxed e-con e-parent\" data-id=\"d17e158\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c3e34c elementor-widget elementor-widget-heading\" data-id=\"5c3e34c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wrzeciono Czasu - skup zegark\u00f3w luksusowych<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-352ee89 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"352ee89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We are interested in buying watches from individuals and companies. We buy watches for cash or bank transfer. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f7a6de1 e-flex e-con-boxed e-con e-parent\" data-id=\"f7a6de1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f780bf5 e-con-full e-flex e-con e-child\" data-id=\"f780bf5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-99467b8 e-con-full e-flex e-con e-child\" data-id=\"99467b8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfeeff4 elementor-widget elementor-widget-text-editor\" data-id=\"cfeeff4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea0dd17 elementor-widget elementor-widget-text-editor\" data-id=\"ea0dd17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Use the contact form<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49fb48d elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"49fb48d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Watch buying form\" aria-label=\"Watch buying form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"175415\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"49fb48d\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Wrzeciono Czasu\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tFull Name\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Full Name\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail address\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email address\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-phone elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-phone\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPhone number\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[phone]\" id=\"form-field-phone\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Phone number\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_64d520a elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_64d520a\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tWatch brand and model\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_64d520a]\" id=\"form-field-field_64d520a\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Watch brand and model\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_4bade81 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_4bade81\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tWatch Reference Number\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_4bade81]\" id=\"form-field-field_4bade81\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Watch Reference Number\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_664bb5c elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_664bb5c\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPackage contents\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_664bb5c]\" id=\"form-field-field_664bb5c\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\">\n\t\t\t\t\t\t\t\t\t<option value=\"Choose options...\">Choose options...<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Watch only\">Watch only<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Watch with papers\">Watch with papers<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Watch with box\">Watch with box<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Watch with box and papers\">Watch with box and papers<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_73c67bb elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_73c67bb\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tFinancial expectations\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_73c67bb]\" id=\"form-field-field_73c67bb\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Financial expectations\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_1a5de41 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_1a5de41\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_1a5de41]\" id=\"form-field-field_1a5de41\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Message\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-upload elementor-field-group elementor-column elementor-field-group-field_2cd95cf elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_2cd95cf\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tAdd photo\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input type=\"file\" name=\"form_fields[field_2cd95cf][]\" id=\"form-field-field_2cd95cf\" class=\"elementor-field elementor-size-sm  elementor-upload-field\" required=\"required\" multiple=\"multiple\" data-maxsize=\"20\" data-maxsize-message=\"This file exceeds the maximum allowed size.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Send<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c6cf9b e-con-full e-flex e-con e-child\" data-id=\"7c6cf9b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e17d9da elementor-widget elementor-widget-text-editor\" data-id=\"e17d9da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-277b777 elementor-widget elementor-widget-text-editor\" data-id=\"277b777\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Visit one of our physical stores<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4daaf91 elementor-widget elementor-widget-heading\" data-id=\"4daaf91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warsaw<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9cacf2 elementor-widget elementor-widget-text-editor\" data-id=\"f9cacf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mokotowka Street 71<\/p><p>Suite 101<br>00-530 Warsaw<\/p><p>Opening hours: <br>Mon-Fri 11:00 AM-7:00 PM<br>Saturday 11:00 AM-5:00 PM<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3a53ee elementor-widget elementor-widget-text-editor\" data-id=\"c3a53ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gda\u0144sk<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10fc9e5 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"10fc9e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Store inside Radisson Blu Hotel<br>ul. D\u0142ugi Targ 19<br>80-828 Gda\u0144sk <br><br>Opening hours: Mon-Fri 11:00-19:00<\/p><p>Please contact us by phone before your visit to confirm the appointment.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d45f7e0 elementor-widget elementor-widget-text-editor\" data-id=\"d45f7e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Krakow<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07eb278 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"07eb278\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Store inside Novotel Krak\u00f3w City West Hotel<br>ul. Armii Krajowej 11 <br><br>Opening hours: Mon-Fri 10:00-14:00<\/p><p>Please contact us by phone before your visit to confirm the appointment.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf3192d elementor-widget elementor-widget-text-editor\" data-id=\"bf3192d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hotline:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-260b5b3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"260b5b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:wrzeciono_czasu@wp.pl\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Email: wrzeciono_czasu@wp.pl<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:512%20301%20928\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Telefon: +48 512 301 928<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-caa762a e-con-full e-flex e-con e-child\" data-id=\"caa762a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-00ec09d elementor-widget elementor-widget-text-editor\" data-id=\"00ec09d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>3<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2cff81 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"c2cff81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Write to us \non Facebook<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fdb65b elementor-widget elementor-widget-html\" data-id=\"1fdb65b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"fb-page\" data-href=\"https:\/\/www.facebook.com\/profile.php?id=100029146076195\" data-tabs=\"timeline\" data-width=\"500\" data-height=\"600\" data-small-header=\"false\" data-adapt-container-width=\"true\" data-hide-cover=\"false\" data-show-facepile=\"true\"><blockquote cite=\"https:\/\/www.facebook.com\/profile.php?id=100029146076195\" class=\"fb-xfbml-parse-ignore\"><a href=\"https:\/\/www.facebook.com\/profile.php?id=100029146076195\">wrzecionoczasu.pl<\/a><\/blockquote><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0a6c3a e-flex e-con-boxed e-con e-parent\" data-id=\"c0a6c3a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d21817 elementor-widget elementor-widget-heading\" data-id=\"2d21817\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">We buy watches<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f9dcf0 elementor-widget elementor-widget-text-editor\" data-id=\"6f9dcf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li class=\"ql-block\" data-block-id=\"block-c9464a30-90f4-4d72-add8-4d74b1b7e44e\">A. Lange  Sohne<\/li><li class=\"ql-block\" data-block-id=\"block-21de8736-1fec-44ef-9d88-61277d956e9a\">Anonymous<\/li><li class=\"ql-block\" data-block-id=\"block-cefbabc5-2290-48ce-a54b-459505ee7872\">Audemars Piguet<\/li><li class=\"ql-block\" data-block-id=\"block-a5c27445-e80a-49a9-a404-34e3a9aee586\">Ball<\/li><li class=\"ql-block\" data-block-id=\"block-000d0985-868e-4dbb-9a53-1b85b5e04fd3\">Baume  Mercier<\/li><li class=\"ql-block\" data-block-id=\"block-85bcd2c8-4a91-4eaa-8f90-56c8446fc388\">Blancpain<\/li><li class=\"ql-block\" data-block-id=\"block-ef51f55b-8fe5-40e6-b7f2-af1e20f964d2\">Bovet<\/li><li class=\"ql-block\" data-block-id=\"block-8c11d658-d196-460d-8a6b-e86c2aa9a451\">Breguet<\/li><li class=\"ql-block\" data-block-id=\"block-13fbd71a-0899-43d1-a6fd-6f3fb94e6c48\">Breitling<\/li><li class=\"ql-block\" data-block-id=\"block-2f5051f9-f9df-4e4e-a75d-49718c44bca8\">Bvlgari<\/li><li class=\"ql-block\" data-block-id=\"block-cf644818-0429-46f1-bdbc-273f12ee08a5\">Cartier<\/li><li class=\"ql-block\" data-block-id=\"block-04d7dea2-5d54-43bd-9ad1-51afc179a626\">Chopard<\/li><li class=\"ql-block\" data-block-id=\"block-81e408d0-4973-4a35-b601-bafbed06d407\">Cvstos<\/li><li class=\"ql-block\" data-block-id=\"block-f606f827-e80a-4444-a447-0788d7add286\">Chronoswiss<\/li><li class=\"ql-block\" data-block-id=\"block-fd540ec1-c1bb-4ee1-8a1d-e8ccbd558ee8\">Corum<\/li><li class=\"ql-block\" data-block-id=\"block-db3d943f-8d04-4f73-b871-99c3ca0131d6\">Daniel Roth<\/li><li class=\"ql-block\" data-block-id=\"block-d39499fa-b1b6-472b-9fd0-fdc2af47a3fe\">DeLaCour<\/li><li class=\"ql-block\" data-block-id=\"block-78dae2f2-9bb8-4f99-903e-cb06a0601856\">DeWitt<\/li><li class=\"ql-block\" data-block-id=\"block-59ed2015-9147-4612-9d86-d534d066b011\">Dubey  Schaldenbrand<\/li><li class=\"ql-block\" data-block-id=\"block-e36ce03f-25c2-4aa7-8e25-4b23a8594cc6\">Epos<\/li><li class=\"ql-block\" data-block-id=\"block-b9edbe31-a9ed-4071-be10-b6c2c0f9de7a\">Eberhard  Co<\/li><li class=\"ql-block\" data-block-id=\"block-7b6096e2-27e0-4876-9572-1d14db3340d1\">F.P. Journe<\/li><li class=\"ql-block\" data-block-id=\"block-3c253231-3baf-49a2-a379-141fb5a02329\">Franck Muller<\/li><li class=\"ql-block\" data-block-id=\"block-41a56e31-399a-494d-a4bc-893c78267dea\">Frederique Constant<\/li><li class=\"ql-block\" data-block-id=\"block-f58f65f4-efa5-4a97-8c57-74fbb201a3fd\">Fortis<\/li><li class=\"ql-block\" data-block-id=\"block-b59c074e-86a6-4e7a-8c44-fee9ab8b72cf\">Gerald Genta<\/li><li class=\"ql-block\" data-block-id=\"block-8154d608-7dc1-4aa2-8896-1da3da5cf9dc\">Geneve<\/li><li class=\"ql-block\" data-block-id=\"block-9239ffd4-eb86-4f6d-98b7-888d2ae739c4\">Grand Seiko<\/li><li class=\"ql-block\" data-block-id=\"block-1fffae68-6e19-48ef-a579-95dd5da610ee\">Graham<\/li><li class=\"ql-block\" data-block-id=\"block-13921add-dd18-4dca-8d45-bbbd97ce5aa5\">Girard Perregaux<\/li><li class=\"ql-block\" data-block-id=\"block-baa88a27-6445-47bd-a76a-eb6d82f6e488\">Glashutte Original<\/li><li class=\"ql-block\" data-block-id=\"block-4f8d1083-9468-481e-874c-af3fb929dd8d\">Glycine<\/li><li class=\"ql-block\" data-block-id=\"block-6bfb41b8-a41f-4cf7-bb29-08e713376ea1\">Harry Winston<\/li><li class=\"ql-block\" data-block-id=\"block-f309d8e1-d943-49f4-8fcd-5f5486c2c675\">Hermes<\/li><li class=\"ql-block\" data-block-id=\"block-d038dead-8b02-4446-a535-70b57740c45d\">Heuer<\/li><li class=\"ql-block\" data-block-id=\"block-d190fd40-0bed-4791-b19e-2a9ec76ee71d\">Hublot<\/li><li class=\"ql-block\" data-block-id=\"block-8d1cc207-65e1-43d0-9ac1-ea912dea2cf0\">Hysek<\/li><li class=\"ql-block\" data-block-id=\"block-e70d9fd9-1d55-467f-b42b-4e856c27fa70\">IWC<\/li><li class=\"ql-block\" data-block-id=\"block-70615bb7-e3e9-4139-a91e-e2c3c0943e79\">Jacob  Co.<\/li><li class=\"ql-block\" data-block-id=\"block-082ccb1b-cb24-4cac-a333-7f5a2808e810\">Jaeger LeCoultre<\/li><li class=\"ql-block\" data-block-id=\"block-55bca3df-b2f3-4d77-8fa9-b113046b1257\">Jaquet Droz<\/li><li class=\"ql-block\" data-block-id=\"block-8f19bc5e-439f-4670-8b9a-3611be9acc3c\">Longines<\/li><li class=\"ql-block\" data-block-id=\"block-7b2b6ab8-b191-4190-985f-22aea46a506e\">Lip<\/li><li class=\"ql-block\" data-block-id=\"block-558c7a51-26d0-491e-b5ac-8ebf7304f164\">Louis Vuitton<\/li><li class=\"ql-block\" data-block-id=\"block-9aca0090-8cb3-45ee-9771-ee478008c19e\">Maurice Lacroix<\/li><li class=\"ql-block\" data-block-id=\"block-2dbe1d5f-447d-4a25-a95f-5ba2c860e57e\">MB<\/li><li class=\"ql-block\" data-block-id=\"block-ce4e1cf7-dda8-4483-8253-a3ebcad66e77\">Montblanc<\/li><li class=\"ql-block\" data-block-id=\"block-f1724b9b-3bcc-4614-98c0-3faa30aa0777\">Nomos<\/li><li class=\"ql-block\" data-block-id=\"block-890e92b5-ed27-4ac8-b0ea-9fb1d93d0022\">Panerai<\/li><li class=\"ql-block\" data-block-id=\"block-087e239a-0f0e-48c2-b6b6-ff6f02f29966\">Parmigiani<\/li><li class=\"ql-block\" data-block-id=\"block-0179dffc-034e-4fdf-a534-cceca13e5979\">Patek Philippe<\/li><li class=\"ql-block\" data-block-id=\"block-052f92e0-465c-48e5-b6b1-6c8f240bd9ad\">Perrelet<\/li><li class=\"ql-block\" data-block-id=\"block-e2dad327-bec5-4258-937f-5c4777ab1573\">Porsche Design<\/li><li class=\"ql-block\" data-block-id=\"block-7a0dd7cf-76ad-4000-95a5-3a6118568529\">Piaget<\/li><li class=\"ql-block\" data-block-id=\"block-67b27f98-5cda-4366-9046-1a3612a6a618\">Rado<\/li><li class=\"ql-block\" data-block-id=\"block-0a029714-2d31-4b96-888b-02e202db7f84\">Raymond Weil<\/li><li class=\"ql-block\" data-block-id=\"block-ec4524b1-845e-4fde-a969-2215b3667096\">Richard Mille<\/li><li class=\"ql-block\" data-block-id=\"block-4be18fdf-f968-4423-80ba-f9bf7bae7b0d\">Roger Dubuis<\/li><li class=\"ql-block\" data-block-id=\"block-f13c25af-2a21-4b3b-9632-f79bfce996e5\">Romain Jerome<\/li><li class=\"ql-block\" data-block-id=\"block-6faf16f3-d62f-4303-b9c7-bc4096b61cfe\">Rolex<\/li><li class=\"ql-block\" data-block-id=\"block-71fec5e7-cf1f-44a8-9897-ff9640cdddb1\">TAG Heuer<\/li><li class=\"ql-block\" data-block-id=\"block-e1bcf14f-495f-4e97-b88f-df4248125e24\">Tudor<\/li><li class=\"ql-block\" data-block-id=\"block-e77c076c-6fb3-472c-962b-2609a75cba11\">Tutima<\/li><li class=\"ql-block\" data-block-id=\"block-c28d881f-6dc1-4f18-9b39-8bdbea4d3671\">Ulysse Nardin<\/li><li class=\"ql-block\" data-block-id=\"block-e3abc605-7ca6-452d-ab71-a0a2fefc7e8b\">Universal Geneve<\/li><li class=\"ql-block\" data-block-id=\"block-f1d62bcc-a7eb-43e9-8dba-520c72664bfb\">Vacheron Constantin<\/li><li class=\"ql-block\" data-block-id=\"block-b7affe30-6b76-403b-9760-ca5194ec1f89\">Van Der Bauwede<\/li><li class=\"ql-block\" data-block-id=\"block-2b6fc8f3-fb99-4d2a-8957-6ec831b67db6\">Wempe<\/li><li class=\"ql-block\" data-block-id=\"block-e72e33ad-d26c-47e1-81dd-4ec33f183b41\">Zenith<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa17897 e-flex e-con-boxed e-con e-parent\" data-id=\"aa17897\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc925a3 elementor-widget elementor-widget-heading\" data-id=\"cc925a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">We DO NOT Buy These Watches<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c37b514 elementor-widget elementor-widget-text-editor\" data-id=\"c37b514\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Adiatica<\/li><li>Adidas<\/li><li>Albert Riele<\/li><li>Apple Watch<\/li><li>Armani<\/li><li>Atlantic<\/li><li>Bulova<\/li><li>Casio<\/li><li>Citizen<\/li><li>Delbana<\/li><li>Diesel<\/li><li>Festina<\/li><li>Fortis<\/li><li>Fossil<\/li><li>Garmin<\/li><li>G-Shock<\/li><li>Guess<\/li><li>Invicta<\/li><li>Maserati<\/li><li>Michael Kors<\/li><li>Lorus<\/li><li>Orient<\/li><li>Q<\/li><li>Roamer<\/li><li>Samsung Galaxy Watch <\/li><li>Seiko<\/li><li>Timex<\/li><li>Tommy Hilfiger<\/li><li>Torii<\/li><li>Versace<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u2039 \u203a Below we present a map of Mokotowska Street with marked parking areas, kindly provided by our partner local newspaper Ave Mokotowska. We buy watches A. Lange Sohne Anonymous Audemars Piguet Ball Baume Mercier Blancpain Bovet Breguet Breitling Bvlgari Cartier Chopard Cvstos Chronoswiss Corum Daniel Roth DeLaCour DeWitt Dubey Schaldenbrand Epos Eberhard Co F.P. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-175422","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Warsaw Salon - Wrzeciono Czasu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Warsaw Salon\" \/>\n<meta property=\"og:description\" content=\"\u2039 \u203a Below we present a map of Mokotowska Street with marked parking areas, kindly provided by our partner local newspaper Ave Mokotowska. We buy watches A. Lange Sohne Anonymous Audemars Piguet Ball Baume Mercier Blancpain Bovet Breguet Breitling Bvlgari Cartier Chopard Cvstos Chronoswiss Corum Daniel Roth DeLaCour DeWitt Dubey Schaldenbrand Epos Eberhard Co F.P. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/\" \/>\n<meta property=\"og:site_name\" content=\"Wrzeciono Czasu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wrzecionoczasupl\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-20T15:51:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2025\/12\/mprzystal_avemokotowska_mapa-1024x744-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"744\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/\",\"url\":\"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/\",\"name\":\"Warsaw Salon - Wrzeciono Czasu\",\"isPartOf\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2025\/12\/mprzystal_avemokotowska_mapa-1024x744-1.png\",\"datePublished\":\"2024-05-29T08:03:31+00:00\",\"dateModified\":\"2026-01-20T15:51:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/#primaryimage\",\"url\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2025\/12\/mprzystal_avemokotowska_mapa-1024x744-1.png\",\"contentUrl\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2025\/12\/mprzystal_avemokotowska_mapa-1024x744-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/wrzecionoczasu.pl\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Warsaw Salon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#website\",\"url\":\"https:\/\/wrzecionoczasu.pl\/en\/\",\"name\":\"Wrzeciono Czasu\",\"description\":\"Wrzeciono Czasu\",\"publisher\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#organization\"},\"alternateName\":\"Wrzeciono Czasu\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wrzecionoczasu.pl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#organization\",\"name\":\"Wrzeciono Czasu\",\"url\":\"https:\/\/wrzecionoczasu.pl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2024\/03\/logo-light1.svg\",\"contentUrl\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2024\/03\/logo-light1.svg\",\"width\":86,\"height\":71,\"caption\":\"Wrzeciono Czasu\"},\"image\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wrzecionoczasupl\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Warsaw Salon - Wrzeciono Czasu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/","og_locale":"en_US","og_type":"article","og_title":"Warsaw Salon","og_description":"\u2039 \u203a Below we present a map of Mokotowska Street with marked parking areas, kindly provided by our partner local newspaper Ave Mokotowska. We buy watches A. Lange Sohne Anonymous Audemars Piguet Ball Baume Mercier Blancpain Bovet Breguet Breitling Bvlgari Cartier Chopard Cvstos Chronoswiss Corum Daniel Roth DeLaCour DeWitt Dubey Schaldenbrand Epos Eberhard Co F.P. [&hellip;]","og_url":"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/","og_site_name":"Wrzeciono Czasu","article_publisher":"https:\/\/www.facebook.com\/wrzecionoczasupl","article_modified_time":"2026-01-20T15:51:20+00:00","og_image":[{"width":1024,"height":744,"url":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2025\/12\/mprzystal_avemokotowska_mapa-1024x744-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/","url":"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/","name":"Warsaw Salon - Wrzeciono Czasu","isPartOf":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/#primaryimage"},"image":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/#primaryimage"},"thumbnailUrl":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2025\/12\/mprzystal_avemokotowska_mapa-1024x744-1.png","datePublished":"2024-05-29T08:03:31+00:00","dateModified":"2026-01-20T15:51:20+00:00","breadcrumb":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/#primaryimage","url":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2025\/12\/mprzystal_avemokotowska_mapa-1024x744-1.png","contentUrl":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2025\/12\/mprzystal_avemokotowska_mapa-1024x744-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/wrzecionoczasu.pl\/en\/warsaw-salon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/wrzecionoczasu.pl\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Warsaw Salon"}]},{"@type":"WebSite","@id":"https:\/\/wrzecionoczasu.pl\/en\/#website","url":"https:\/\/wrzecionoczasu.pl\/en\/","name":"Wrzeciono Czasu","description":"Wrzeciono Czasu","publisher":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/#organization"},"alternateName":"Wrzeciono Czasu","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wrzecionoczasu.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wrzecionoczasu.pl\/en\/#organization","name":"Wrzeciono Czasu","url":"https:\/\/wrzecionoczasu.pl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wrzecionoczasu.pl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2024\/03\/logo-light1.svg","contentUrl":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2024\/03\/logo-light1.svg","width":86,"height":71,"caption":"Wrzeciono Czasu"},"image":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wrzecionoczasupl"]}]}},"_links":{"self":[{"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/pages\/175422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/comments?post=175422"}],"version-history":[{"count":6,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/pages\/175422\/revisions"}],"predecessor-version":[{"id":194994,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/pages\/175422\/revisions\/194994"}],"wp:attachment":[{"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/media?parent=175422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}