
{"id":199356,"date":"2026-02-23T18:35:55","date_gmt":"2026-02-23T17:35:55","guid":{"rendered":"https:\/\/wrzecionoczasu.pl\/?post_type=product&#038;p=199356"},"modified":"2026-02-23T18:40:59","modified_gmt":"2026-02-23T17:40:59","slug":"vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia","status":"publish","type":"product","link":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/","title":{"rendered":"Vacheron Constantin 1972 Asymmetric 25021 Lady 18k White Gold 23mm"},"content":{"rendered":"<p>PRE-OWNED LADIES WATCH<br \/>\nVACHERON CONSTANTIN 1972 ASYMMETRIC<br \/>\nQUARTZ<br \/>\n18K|750 WHITE GOLD<br \/>\nRef. No.: 25021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pre-owned Swiss Vacheron Constantin 1972 Asymmetric 25021 watch<\/p>\n","protected":false},"featured_media":199364,"template":"","meta":{"_acf_changed":false,"content-type":""},"seria":[],"product_brand":[],"product_cat":[1150,1268],"product_tag":[1040],"class_list":["post-199356","product","type-product","status-publish","has-post-thumbnail","product_cat-brands","product_cat-vacheron-constantin","product_tag-warszawa","pa_damski-meski-unisex-damski","pa_dokumentacja-no-manufacturers-documents-wrzeciono-czasu-purchase-confirmation","pa_gwarancja-1-year-wrzeciono-czasu-warranty","pa_kolor-tarczy-mother-of-pearl","pa_marka-vacheron-constantin-en","pa_material-paska-leather","pa_material-zapiecia-gold","pa_material-zegarka-white-gold","pa_mechanizm-quartz","pa_pasek-replacement","pa_pudelko-etui-zastepcze","pa_rodzaj-paska-pasek","pa_rodzaj-zapiecia-buckle","pa_stan-paska-very-good","pa_stan-zegarka-good","pa_szklo-szafirowe","pa_typ-zegarka-nareczny","pa_wodoszczelnosc-3atm-en","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vacheron Constantin 1972 Asymmetric 25021 Lady 18k White Gold 23mm - Wrzeciono Czasu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vacheron Constantin 1972 Asymmetric 25021 Lady 18k White Gold 23mm\" \/>\n<meta property=\"og:description\" content=\"Pre-owned Swiss Vacheron Constantin 1972 Asymmetric 25021 watch\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/\" \/>\n<meta property=\"og:site_name\" content=\"Wrzeciono Czasu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wrzecionoczasupl\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T17:40:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/02\/0D3A7770.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&#036;7 099\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/\",\"url\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/\",\"name\":\"Vacheron Constantin 1972 Asymmetric 25021 Lady 18k White Gold 23mm - Wrzeciono Czasu\",\"isPartOf\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/02\/0D3A7770.jpg\",\"datePublished\":\"2026-02-23T17:35:55+00:00\",\"dateModified\":\"2026-02-23T17:40:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/#primaryimage\",\"url\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/02\/0D3A7770.jpg\",\"contentUrl\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/02\/0D3A7770.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/wrzecionoczasu.pl\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/wrzecionoczasu.pl\/en\/shop-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vacheron Constantin 1972 Asymmetric 25021 Lady 18k White Gold 23mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#website\",\"url\":\"https:\/\/wrzecionoczasu.pl\/en\/\",\"name\":\"Wrzeciono Czasu\",\"description\":\"Wrzeciono Czasu\",\"publisher\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#organization\"},\"alternateName\":\"Wrzeciono Czasu\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wrzecionoczasu.pl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#organization\",\"name\":\"Wrzeciono Czasu\",\"url\":\"https:\/\/wrzecionoczasu.pl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2024\/03\/logo-light1.svg\",\"contentUrl\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2024\/03\/logo-light1.svg\",\"width\":86,\"height\":71,\"caption\":\"Wrzeciono Czasu\"},\"image\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wrzecionoczasupl\"]}]}<\/script>\n<meta property=\"product:price:amount\" content=\"7099\" \/>\n<meta property=\"product:price:currency\" content=\"USD\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"Vacheron Constantin a75 N1123\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vacheron Constantin 1972 Asymmetric 25021 Lady 18k White Gold 23mm - Wrzeciono Czasu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/","og_locale":"en_US","og_type":"article","og_title":"Vacheron Constantin 1972 Asymmetric 25021 Lady 18k White Gold 23mm","og_description":"Pre-owned Swiss Vacheron Constantin 1972 Asymmetric 25021 watch","og_url":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/","og_site_name":"Wrzeciono Czasu","article_publisher":"https:\/\/www.facebook.com\/wrzecionoczasupl","article_modified_time":"2026-02-23T17:40:59+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/02\/0D3A7770.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&#36;7 099","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/","url":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/","name":"Vacheron Constantin 1972 Asymmetric 25021 Lady 18k White Gold 23mm - Wrzeciono Czasu","isPartOf":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/#primaryimage"},"image":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/#primaryimage"},"thumbnailUrl":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/02\/0D3A7770.jpg","datePublished":"2026-02-23T17:35:55+00:00","dateModified":"2026-02-23T17:40:59+00:00","breadcrumb":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/#primaryimage","url":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/02\/0D3A7770.jpg","contentUrl":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/02\/0D3A7770.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/vacheron-constantin-1972-asymmetric-lady-18k-rose-gold-23mm-kopia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/wrzecionoczasu.pl\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/wrzecionoczasu.pl\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"Vacheron Constantin 1972 Asymmetric 25021 Lady 18k White Gold 23mm"}]},{"@type":"WebSite","@id":"https:\/\/wrzecionoczasu.pl\/en\/#website","url":"https:\/\/wrzecionoczasu.pl\/en\/","name":"Wrzeciono Czasu","description":"Wrzeciono Czasu","publisher":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/#organization"},"alternateName":"Wrzeciono Czasu","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wrzecionoczasu.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wrzecionoczasu.pl\/en\/#organization","name":"Wrzeciono Czasu","url":"https:\/\/wrzecionoczasu.pl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wrzecionoczasu.pl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2024\/03\/logo-light1.svg","contentUrl":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2024\/03\/logo-light1.svg","width":86,"height":71,"caption":"Wrzeciono Czasu"},"image":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wrzecionoczasupl"]}]},"product_price_amount":"7099","product_price_currency":"USD","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"Vacheron Constantin a75 N1123","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/product\/199356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/media\/199364"}],"wp:attachment":[{"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/media?parent=199356"}],"wp:term":[{"taxonomy":"seria","embeddable":true,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/seria?post=199356"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/product_brand?post=199356"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/product_cat?post=199356"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/product_tag?post=199356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}