
{"id":203437,"date":"2026-03-27T14:20:31","date_gmt":"2026-03-27T13:20:31","guid":{"rendered":"https:\/\/wrzecionoczasu.pl\/?post_type=product&#038;p=203437"},"modified":"2026-03-27T14:28:10","modified_gmt":"2026-03-27T13:28:10","slug":"franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia","status":"publish","type":"product","link":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/","title":{"rendered":"Franck Muller Long Island Lady 900 QZ D Quartz Diamonds 18k Gold 23mm x 40mm"},"content":{"rendered":"<p>PRE-OWNED LADIES&#8217; WATCH<br \/>\nFRANCK MULLER LONG ISLAND LADY<br \/>\nQUARTZ<br \/>\nGOLD 18K|750\/DIAMONDS<br \/>\nRef. No.: 900 QZ D<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pre-owned Swiss Franck Muller Long Island Lady 900 QZ D watch<\/p>\n","protected":false},"featured_media":203445,"template":"","meta":{"_acf_changed":false,"content-type":""},"seria":[],"product_brand":[],"product_cat":[1150,1201],"product_tag":[1275],"class_list":["post-203437","product","type-product","status-publish","has-post-thumbnail","product_cat-brands","product_cat-franck-muller","product_tag-warszawa-en","pa_damski-meski-unisex-womens","pa_dokumentacja-no-manufacturers-documents-wrzeciono-czasu-purchase-confirmation","pa_gwarancja-1-year-wrzeciono-czasu-warranty","pa_kolor-tarczy-silver","pa_marka-franck-muller-en","pa_material-paska-leather","pa_material-zapiecia-gold","pa_material-zegarka-gold","pa_mechanizm-quartz","pa_pasek-manufacturers","pa_pudelko-replacement-case","pa_rodzaj-paska-strap","pa_rodzaj-zapiecia-buckle","pa_stan-paska-decent","pa_stan-zegarka-good","pa_szklo-sapphire","pa_typ-zegarka-wristwatch","pa_wodoszczelnosc-3atm-en","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Franck Muller Long Island Lady 900 QZ D Quartz Diamonds 18k Gold 23mm x 40mm - Wrzeciono Czasu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Franck Muller Long Island Lady 900 QZ D Quartz Diamonds 18k Gold 23mm x 40mm\" \/>\n<meta property=\"og:description\" content=\"Pre-owned Swiss Franck Muller Long Island Lady 900 QZ D watch\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/\" \/>\n<meta property=\"og:site_name\" content=\"Wrzeciono Czasu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wrzecionoczasupl\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T13:28:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/03\/0D3A2512.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&#036;5 258\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/\",\"url\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/\",\"name\":\"Franck Muller Long Island Lady 900 QZ D Quartz Diamonds 18k Gold 23mm x 40mm - Wrzeciono Czasu\",\"isPartOf\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/03\/0D3A2512.jpg\",\"datePublished\":\"2026-03-27T13:20:31+00:00\",\"dateModified\":\"2026-03-27T13:28:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/#primaryimage\",\"url\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/03\/0D3A2512.jpg\",\"contentUrl\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/03\/0D3A2512.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/wrzecionoczasu.pl\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/wrzecionoczasu.pl\/en\/shop-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Franck Muller Long Island Lady 900 QZ D Quartz Diamonds 18k Gold 23mm x 40mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#website\",\"url\":\"https:\/\/wrzecionoczasu.pl\/en\/\",\"name\":\"Wrzeciono Czasu\",\"description\":\"Wrzeciono Czasu\",\"publisher\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#organization\"},\"alternateName\":\"Wrzeciono Czasu\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wrzecionoczasu.pl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#organization\",\"name\":\"Wrzeciono Czasu\",\"url\":\"https:\/\/wrzecionoczasu.pl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2024\/03\/logo-light1.svg\",\"contentUrl\":\"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2024\/03\/logo-light1.svg\",\"width\":86,\"height\":71,\"caption\":\"Wrzeciono Czasu\"},\"image\":{\"@id\":\"https:\/\/wrzecionoczasu.pl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wrzecionoczasupl\"]}]}<\/script>\n<meta property=\"product:price:amount\" content=\"5258\" \/>\n<meta property=\"product:price:currency\" content=\"USD\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"Franck Muller a139 K1456\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Franck Muller Long Island Lady 900 QZ D Quartz Diamonds 18k Gold 23mm x 40mm - Wrzeciono Czasu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/","og_locale":"en_US","og_type":"article","og_title":"Franck Muller Long Island Lady 900 QZ D Quartz Diamonds 18k Gold 23mm x 40mm","og_description":"Pre-owned Swiss Franck Muller Long Island Lady 900 QZ D watch","og_url":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/","og_site_name":"Wrzeciono Czasu","article_publisher":"https:\/\/www.facebook.com\/wrzecionoczasupl","article_modified_time":"2026-03-27T13:28:10+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/03\/0D3A2512.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&#36;5 258","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/","url":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/","name":"Franck Muller Long Island Lady 900 QZ D Quartz Diamonds 18k Gold 23mm x 40mm - Wrzeciono Czasu","isPartOf":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/#primaryimage"},"image":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/#primaryimage"},"thumbnailUrl":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/03\/0D3A2512.jpg","datePublished":"2026-03-27T13:20:31+00:00","dateModified":"2026-03-27T13:28:10+00:00","breadcrumb":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/#primaryimage","url":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/03\/0D3A2512.jpg","contentUrl":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2026\/03\/0D3A2512.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/wrzecionoczasu.pl\/en\/produkt\/franck-muller-cintree-curvex-manual-7502-s6-mm-d-18k-gold-diamonds-28mm-kopia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/wrzecionoczasu.pl\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/wrzecionoczasu.pl\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"Franck Muller Long Island Lady 900 QZ D Quartz Diamonds 18k Gold 23mm x 40mm"}]},{"@type":"WebSite","@id":"https:\/\/wrzecionoczasu.pl\/en\/#website","url":"https:\/\/wrzecionoczasu.pl\/en\/","name":"Wrzeciono Czasu","description":"Wrzeciono Czasu","publisher":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/#organization"},"alternateName":"Wrzeciono Czasu","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wrzecionoczasu.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wrzecionoczasu.pl\/en\/#organization","name":"Wrzeciono Czasu","url":"https:\/\/wrzecionoczasu.pl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wrzecionoczasu.pl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2024\/03\/logo-light1.svg","contentUrl":"https:\/\/wrzecionoczasu.pl\/wp-content\/uploads\/2024\/03\/logo-light1.svg","width":86,"height":71,"caption":"Wrzeciono Czasu"},"image":{"@id":"https:\/\/wrzecionoczasu.pl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wrzecionoczasupl"]}]},"product_price_amount":"5258","product_price_currency":"USD","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"Franck Muller a139 K1456","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/product\/203437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/media\/203445"}],"wp:attachment":[{"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/media?parent=203437"}],"wp:term":[{"taxonomy":"seria","embeddable":true,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/seria?post=203437"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/product_brand?post=203437"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/product_cat?post=203437"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wrzecionoczasu.pl\/en\/wp-json\/wp\/v2\/product_tag?post=203437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}